{"id":387736,"date":"2019-05-14T07:50:21","date_gmt":"2019-05-14T05:50:21","guid":{"rendered":"http:\/\/we-search.be\/?p=387736"},"modified":"2019-06-16T16:37:26","modified_gmt":"2019-06-16T14:37:26","slug":"pourquoi-on-migre-de-linegale-legitimite-des-mobilites","status":"publish","type":"post","link":"https:\/\/we-search.be\/index.php\/2019\/05\/14\/pourquoi-on-migre-de-linegale-legitimite-des-mobilites\/","title":{"rendered":"Pourquoi on migre \u2013 de l\u2019in\u00e9gale l\u00e9gitimit\u00e9 des mobilit\u00e9s"},"content":{"rendered":"\n<h5 class=\"wp-block-heading\">Par&nbsp;<em>Elo\u00efse&nbsp;Goffart,&nbsp;dipl\u00f4m\u00e9e&nbsp;en&nbsp;sciences&nbsp;politiques<\/em><\/h5>\n\n\n\n<p><strong>Je suis n\u00e9e dans l\u2019espace Schengen. <\/strong>Mon enfance \u00e9tait confortablement berc\u00e9e de s\u00e9jours dans les stations de ski alpines en France, de visites aux amis allemands de ma m\u00e8re, d\u2019\u00e9t\u00e9s \u00e0 Montr\u00e9al chez mes grands-parents. J\u2019avais peu de conscience des fronti\u00e8res en tant qu\u2019entit\u00e9s pertinentes \u00e0 mon existence. Quand on rentrait de France, je ne remarquais le passage en Belgique que par le rythme des lampadaires orang\u00e9s bordant l\u2019autoroute. On pourrait classer ma mobilit\u00e9 en plusieurs cat\u00e9gories&nbsp;: tourisme, visite \u00e0 la famille et aux amis, \u00e9tudes, et r\u00e9cemment, travail\/famille\/\u00e9tudes\/tourisme tout \u00e0 la fois. Le point commun, c\u2019est que <strong>toutes ces formes de mobilit\u00e9 ont toujours \u00e9t\u00e9 non seulement possibles <\/strong>(j\u2019ai acc\u00e8s aux technologies du train, de l\u2019avion, de la voiture), <strong>mais aussi permises <\/strong>(deux fois seulement ais-je eu besoin d\u2019un visa, qui m\u2019a \u00e9t\u00e9 offert sur un plateau d\u2019argent), et surtout l\u00e9gitimes, voir encourag\u00e9es. <strong>Partir, c\u2019\u00e9tait bon et souhaitable pour moi, selon ma famille, le service mobilit\u00e9 de l\u2019unif, les m\u00e9dias. <\/strong>Si ma mobilit\u00e9 \u00e9tait bonne et souhaitable pour l\u2019Etat, l\u2019environnement et la communaut\u00e9 o\u00f9 je m\u2019en allais, l\u00e0 n\u2019\u00e9tait pas la question. Aujourd\u2019hui, en Occident, chacun.e a le droit d\u2019\u00e9mettre une opinion sur la l\u00e9gitimit\u00e9 et la d\u00e9sirabilit\u00e9 des personnes qui migrent vers \u00ab&nbsp;chez&nbsp;nous&nbsp;\u00bb. Apr\u00e8s tout, c\u2019est \u00ab&nbsp;chez nous&nbsp;\u00bb, non&nbsp;? <strong>Alors pourquoi personne n\u2019a jamais \u00e9valu\u00e9 la l\u00e9gitimit\u00e9 et la d\u00e9sirabilit\u00e9 de mes migrations&nbsp;? <\/strong>Et plus encore, pourquoi avons-nous \u00e9galement le droit de juger de la l\u00e9gitimit\u00e9 et la d\u00e9sirabilit\u00e9 de nos propres migrations vers ailleurs, ou plut\u00f4t pourquoi celles-ci semblent-elles aller <em>de soi<\/em>&nbsp;? <\/p>\n\n\n\n<p><strong>Certains syst\u00e8mes d\u2019immigration ont la cote. <\/strong>Celui du Canada, par exemple. Depuis longtemps,<strong> le Canada porte un double discours utilitaire et humanitaire sur l\u2019immigration. <\/strong>Celle-ci devrait, d\u2019une part servir les int\u00e9r\u00eats de la nation, sous forme de travailleurs\/euses tri\u00e9.e.s sur le volet en fonction de la correspondance entre les demandes actuelles du march\u00e9 du travail et d\u2019autre part, prendre son lot de mis\u00e8re du monde, sous forme de quelques milliers de r\u00e9fugi\u00e9.e.s r\u00e9install\u00e9.e.s<a href=\"#_ftn1\">[1]<\/a>, dont une partie toujours plus grande est prise en charge par des associations ou des particuliers. La rh\u00e9torique est aguichante&nbsp;: <strong>en acceptant seulement celles et ceux qui pourront facilement s\u2019ins\u00e9rer dans le march\u00e9 du travail, nous leur garantissons une int\u00e9gration \u00e9conomique. <\/strong>Mais nous sommes aussi humains, d\u2019ailleurs notre premier ministre accueillent les r\u00e9fugi\u00e9.e.s \u00e0 l\u2019a\u00e9roport<a href=\"#_ftn2\">[2]<\/a>. Le Canada jouit d\u2019une r\u00e9putation internationale de multiculturalisme et d\u2019humanisme aid\u00e9e par le contraste avec les d\u00e9rives de son voisin am\u00e9ricain. <\/p>\n\n\n\n<p>Cependant, <strong>le syst\u00e8me d\u2019immigration est en r\u00e9alit\u00e9 bien moins \u00e9galitaire, et bas\u00e9 sur une vision tr\u00e8s n\u00e9olib\u00e9rale de l\u2019individu comme ressource. <\/strong>L\u2019Australie, bien plus vocale sur son refus d\u2019accueillir des demandeurs d\u2019asile, a, elle aussi un syst\u00e8me d\u2019immigration bas\u00e9 sur les qualifications, publiant une liste des professions en demande. Les personnes correspondant \u00e0 ces cat\u00e9gories gagnent des points qui leur permettront, peut-\u00eatre, d\u2019obtenir un <em>highly skilled visa<\/em>. <strong>On est en droit de se questionner sur la coh\u00e9rence de tels syst\u00e8mes, \u00e0 un moment o\u00f9 le discours entourant les migrations est de plus en plus phras\u00e9 en termes d\u2019identit\u00e9, d\u2019int\u00e9gration, et de culture.<\/strong> Ces politiques d\u2019immigration consid\u00e8rent les potentiel.le.s immigrant.e.s comme des solutions \u00e0 un manque de main d\u2019\u0153uvre, et non comme des individus humains portant une histoire et des attentes&nbsp;; d\u00e8s qu\u2019ils et elles ne servent plus une fonction \u00e9conomique, ils et elles sont ramen\u00e9.e.s \u00e0 leurs diff\u00e9rences, qui semblent soudain insurmontables.<\/p>\n\n\n\n<p>Qu\u2019en est-il de la\ncat\u00e9gorie des r\u00e9fugi\u00e9.e.s, personnes sous protection subsidiaire<a href=\"#_ftn3\">[3]<\/a>\net autres visa humanitaires&nbsp;? N\u2019est-ce pas l\u00e0 la preuve de la b\u00e9n\u00e9volence\nd\u00e9sint\u00e9ress\u00e9e de l\u2019Etat et de ces citoyens&nbsp;? La r\u00e9alit\u00e9 n\u2019est pas si\nsimple. Plusieurs auteur.e.s<a href=\"#_ftn4\">[4]<\/a>\nont mis en \u00e9vidence le changement discursif autour des r\u00e9fugi\u00e9.e.s apr\u00e8s la\nguerre froide. Pour faire simple, la p\u00e9riode de la guerre froide donnait une\nimage de bastion des droits humains aux Etats accueillant des r\u00e9fugi\u00e9.e.s en\nprovenance du monde communiste. Les r\u00e9fugi\u00e9.e.s \u00e9taient donc une ressource\nhaute en capital symbolique pour les nations capitalistes et communistes en\ncomp\u00e9tition. En t\u00e9moigne la baisse dramatique des demandes d\u2019asile accept\u00e9e d\u00e8s\nle d\u00e9but des ann\u00e9es 90 \u2013 en France, le ratio est soudain pass\u00e9 de 80% d\u2019accord\n\u00e0 20%<a href=\"#_ftn5\">[5]<\/a>.\n<\/p>\n\n\n\n<p><strong>La rh\u00e9torique humaniste est encore mobilis\u00e9e, comme dans le cas r\u00e9cent de Rahaf Mohammed al-Qunun, adolescente saoudienne, qui, ayant fui sa famille violente, a re\u00e7u l\u2019asile au Canada<\/strong> dans une proc\u00e9dure acc\u00e9l\u00e9r\u00e9e gr\u00e2ce \u00e0 la grande m\u00e9diatisation de son cas. Beaucoup ont critiqu\u00e9 les motifs sous-jacents de la d\u00e9cision du Canada, et sa c\u00e9l\u00e9bration par des figures anti-immigration et islamophobes<a href=\"#_ftn6\">[6]<\/a>. <strong>Le r\u00e9cit a \u00e9t\u00e9, en effet, tr\u00e8s m\u00e9diatis\u00e9 et cadr\u00e9 comme une victoire de la libert\u00e9 occidentale sur l\u2019obscurantisme islamique<\/strong> \u2013 ce qui tombait \u00e0 point pour redorer le blason du Canada, quelques mois apr\u00e8s son refus de mettre fin \u00e0 la vente tr\u00e8s profitable de tanks de guerre \u00e0 l\u2019Arabie Saoudite juste apr\u00e8s le meurtre du journaliste Khashoggi. <\/p>\n\n\n\n<p><strong>La valeur id\u00e9ologique des r\u00e9fugi\u00e9.e.s, bien que pouvant \u00eatre manipul\u00e9e dans des cas individuels, n\u2019est cependant plus du tout automatique. Au mieux (ou au pire, selon les visions), c\u2019est leur valeur \u00e9conomique qui est mise en avant<\/strong><a href=\"#_ftn7\">[7]<\/a>. Mais penser que les personnes d\u00e9plac\u00e9es de force, du fait de leur statut, existent en dehors des aspirations \u00e9conomiques des pays d\u2019accueil est une illusion. La sociologue Karen Akoka a montr\u00e9 comment les fronti\u00e8res se brouillent, puisque l\u2019octroi quasi automatique (97 \u00e0&nbsp; 99%) de l\u2019asile aux <em>boat people <\/em>d\u2019ex-Indochine dans les ann\u00e9es 80 a \u00e9galement servi \u00e0 renflouer le besoin de main d\u2019\u0153uvre bon march\u00e9 dans certains secteurs industriels<a href=\"#_ftn8\">[8]<\/a>. <strong>Le paradigme actuel accuse beaucoup demandeurs.euses d\u2019asile d\u2019\u00eatre en r\u00e9alit\u00e9 en qu\u00eate d\u2019activit\u00e9 \u00e9conomique, mais l\u2019inverse a toujours \u00e9t\u00e9 le cas&nbsp;: les \u00c9tats voient les immigrant.e.s comme des ressources \u00e9conomiques qu\u2019importe leur statut, et les s\u00e9lectionne parfois dans cette optique sous couvert de discours humanitaire.<\/strong> Prenons par exemple les crit\u00e8res de s\u00e9lection des r\u00e9fugi\u00e9s r\u00e9install\u00e9s impos\u00e9s par l\u2019Allemagne au HCR&nbsp;: en plus des crit\u00e8res de bases (de vuln\u00e9rabilit\u00e9), l\u2019Allemagne donne la priorit\u00e9 aux personnes qui respectent les crit\u00e8res d\u2019int\u00e9gration, c\u2019est-\u00e0-dire sont hautement qualifi\u00e9es, ont de l\u2019exp\u00e9rience professionnelle et parlent allemand<a href=\"#_ftn9\">[9]<\/a>. Le cas est int\u00e9ressant puisque la r\u00e9installation est un m\u00e9canisme du HCR mis en place pour traiter les cas les plus vuln\u00e9rables et urgents, comme les personnes handicap\u00e9es, les enfants, les personnes \u00e2g\u00e9es, etc. Et pourtant, puisqu\u2019il repose uniquement sur les places offertes volontairement par les Etats, ceux-ci op\u00e8rent en effet une s\u00e9lection opportuniste qui semble profond\u00e9ment contraire \u00e0 la raison d\u2019\u00eatre de la r\u00e9installation.<strong> Les soci\u00e9t\u00e9s Occidentales ne sont pas soudainement devenues hostiles aux r\u00e9fugi\u00e9.e.s simplement par choc des civilisation ou repli identitaire, mais parce que les Etats ent\u00e9rinent des politiques et des discours hostiles \u00e0 celles et ceux qui sont devenu.e.s inutiles \u00e0 leurs desseins \u00e9conomiques et politiques.<\/strong> <\/p>\n\n\n\n<p>Autant les discours pour ou contre l\u2019immigration, les tirades sur la d\u00e9fense de la souverainet\u00e9 nationale, de l\u2019\u00e9conomie et de l\u2019int\u00e9grit\u00e9 culturelle pullulent, autant <strong>le silence autour de l\u2019\u00e9migration est assourdissant.<\/strong> Comme le rappelle Catherine Withol de Wenden, nous sommes pass\u00e9.e.s d\u2019un paradigme de contr\u00f4le de l\u2019\u00e9migration \u00e0 celui du contr\u00f4le de l\u2019immigration. Nous allons m\u00eame jusqu\u2019\u00e0 nous arroger le droit de participer au contr\u00f4le de l\u2019\u00e9migration des pays desquels nous ne d\u00e9sirons pas voir arriver les ressortissant.e.s \u2013 ce faisant nous exportons nos fronti\u00e8res, comme l\u2019Australie qui garde ses demandeurs\/euses d\u2019asile dans des camps de d\u00e9tention sur les \u00eeles environnantes<a href=\"#_ftn10\">[10]<\/a>. De m\u00eame, les politiques d\u2019immigration dont le but est d\u2019attirer les personnes hautement qualifi\u00e9es de certains pays moins riches ont \u00e9t\u00e9 critiqu\u00e9es ces derni\u00e8res ann\u00e9es pour leur effet de <em>brain drain<\/em>. Mais m\u00eames ces critiques ne d\u00e9passent pas le paradigme que j\u2019ai expos\u00e9<a href=\"http:\/\/we-search.be\/index.php\/2019\/02\/20\/nommer-la-migration\/\"> dans l\u2019article pr\u00e9c\u00e9dent<\/a>: <strong>les migrations Sud-Nord sont consid\u00e9r\u00e9es comme des ph\u00e9nom\u00e8nes collectifs, les travailleurs et travailleuses qualifi\u00e9es sont in\u00e9vitablement consid\u00e9r\u00e9es comme des ressources, que ce soit pour leur pays d\u2019\u00e9migration ou celui d\u2019immigration.<\/strong> Ma nationalit\u00e9, ma couleur de peau, et mon statut socio-\u00e9conomique sont tous des aspects qui me permettent d\u2019\u00e9chapper \u00e0 cet examen constant du bien-fond\u00e9 de ma mobilit\u00e9. <strong>Personne n\u2019a mentionn\u00e9 que mon d\u00e9part pour le Canada ferait perdre une main d\u2019\u0153uvre n\u00e9cessaire \u00e0 la Belgique, ni que je risquerais de concurrencer les travailleurs et travailleuses qu\u00e9b\u00e9cois.es. <\/strong><\/p>\n\n\n\n<p>Rarement questionnons-nous non plus nos voyages de loisir. &nbsp;<strong>Quand nous nous d\u00e9pla\u00e7ons dans d\u2019autres pays en tant que touristes, nous sommes persuad\u00e9.e.s que nous participons \u00e0 l\u2019\u00e9conomie et au bien-\u00eatre des habitant.e.s locales<\/strong>, et pourtant, de l\u2019impact environnemental des kilom\u00e8tres de bouchons sur les autoroutes de France en Juillet \u00e0 l\u2019exploitation subie par les employ\u00e9.e.s des compagnies a\u00e9riennes low cost en passant par l\u2019escalade des prix de l\u2019immobilier caus\u00e9e par Airbnb et la destruction des \u00e9cosyst\u00e8mes par l\u2019\u00e9tablissement d\u2019h\u00f4tels <em>all inclusive <\/em>sur les \u00eeles du Pacifique, les effets n\u00e9gatifs sont abondants. <strong>Il nous para\u00eetrait incongru de se voir refuser l\u2019acc\u00e8s \u00e0 un pays en tant que touriste, par crainte que l\u2019on endommage l\u2019\u00e9conomie locale ou que l\u2019on ne puisse s\u2019int\u00e9grer correctement,<\/strong> mais l\u2019ann\u00e9e 2018 a comptabilis\u00e9 plus de 1.4 milliard de touristes<a href=\"#_ftn11\">[11]<\/a>&nbsp;; l\u2019impact de ce type de mobilit\u00e9, bien que limit\u00e9 dans le temps, devrait, en toute logique, \u00eatre bien plus inqui\u00e9tant que celui des 28.5 millions de r\u00e9fugi\u00e9.e.s et demandeurs\/euses d\u2019asile<a href=\"#_ftn12\">[12]<\/a>. <strong>Les voyages \u00e0 but humanitaires sont-ils le dernier bastion de la mobilit\u00e9 b\u00e9n\u00e9fique et d\u00e9sint\u00e9ress\u00e9e&nbsp;? <\/strong>L\u00e0 encore, des chercheurs\/euses mettent en \u00e9vidence les aspects probl\u00e9matiques du <em>volontourisme<\/em>, pratique de payer pour passer quelques semaines ou jours \u00e0 travailler b\u00e9n\u00e9volement dans un \u00ab&nbsp;pays en d\u00e9veloppement&nbsp;\u00bb. Qui n\u2019a pas l\u2019une ou l\u2019autre connaissance ayant pay\u00e9 pour passer deux semaines \u00e0 s\u2019occuper d\u2019enfants dans un orphelinat en Ha\u00efti&nbsp;? <strong>Ce genre de pratique participe au maintien de ces institutions qui ont virtuellement cess\u00e9 d\u2019exister en Occident parce qu\u2019on les reconnait comme lieux de potentiels abus&nbsp;<\/strong>; de plus, les enfants s\u2019y retrouvant ne sont fr\u00e9quemment m\u00eame pas orphelins<a href=\"#_ftn13\">[13]<\/a>. De plus, la pratique du volontourisme de court terme s\u2019av\u00e8re souvent \u00eatre un <strong>gaspillage de ressources, puisque beaucoup d\u2019argent est d\u00e9pens\u00e9 pour que des personnes n\u2019ayant la connaissance ni de la langue ni de la culture locale, et encore moins les qualifications requises, performent des t\u00e2ches qui pourraient \u00eatre remplies par des personnes locales contre salaire<\/strong>, ce qui stimulerait l\u2019\u00e9conomie. Si les volontouristes partent avec un r\u00e9el d\u00e9sir d\u2019apporter une aide significative, nous ne pouvons n\u00e9anmoins collectivement pas nous d\u00e9faire de notre histoire colonialiste<a href=\"#_ftn14\">[14]<\/a>, et je doute qu\u2019un voyage de deux semaines en Tha\u00eflande puisse fondamentalement alt\u00e9rer la structure des in\u00e9galit\u00e9s mondiale. Parce que les entreprises qui vendent ce type de voyages les aur\u00e9olent de promesses de \u00ab&nbsp;faire une diff\u00e9rence&nbsp;\u00bb, \u00ab&nbsp;vivre une exp\u00e9rience, etc., il semble difficile de critiquer ces pratiques&nbsp;; mais il reste que <strong>c\u2019est encore une mani\u00e8re d\u2019externaliser les co\u00fbts du d\u00e9veloppement en vendant un produit aux consommateurs occidentaux, tout en d\u00e9politisant la pauvret\u00e9 par une narration qui veut que le d\u00e9veloppement soit le fruit d\u2019action individuelles et non de g\u00e9opolitique.<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>J<strong>e ne veux pas d\u00e9moniser l\u2019Occident. Bien d\u2019autres Etats prennent part aux dynamiques profond\u00e9ment in\u00e9gales des migrations <\/strong>\u2013 de l\u2019Etat philippin qui encourage massivement l\u2019\u00e9migration de jeunes femmes pour travailler comme aide domestique dans des conditions d\u2019esclavage moderne, aux pays du Golfe qui exploitent massivement la main d\u2019\u0153uvre \u00e9trang\u00e8re gr\u00e2ce au syst\u00e8me de <em>kafala <\/em>o\u00f9 un employeur sponsorise le visa d\u2019un travailleur (et confisque r\u00e9guli\u00e8rement le passeport)<a href=\"#_ftn15\">[15]<\/a>. Mais force est de constater que les personnes provenant des pays riches ont un levier d\u00e9mesur\u00e9ment puissant sur les r\u00e9gimes des migrations. Je voulais soulever deux choses&nbsp;:<strong> 1) Les pratiques de mobilit\u00e9 auxquelles nous, Occidentaux\/ales, participons, sont aussi, par bien des aspects, probl\u00e9matiques, et 2) Nous n\u2019examinons pas ou peu la possibilit\u00e9 que nos propres migrations soient probl\u00e9matiques&nbsp;<\/strong>; tout se passe comme si notre mobilit\u00e9 n\u2019\u00e9tait pas <em>mati\u00e8re \u00e0 discuter.<\/em><\/p>\n\n\n\n<p>Je voudrais revenir \u00e0 ma situation. Si l\u2019on filtre mes diff\u00e9rentes migrations \u00e0 la lumi\u00e8re de mon utilit\u00e9 au pays d\u2019immigration, on se rend compte que <strong>j\u2019ai \u00e9t\u00e9 une immigrante profond\u00e9ment inutile<\/strong>. Quand j\u2019ai v\u00e9cu aux Etats-Unis, j\u2019ai profit\u00e9 d\u2019un an de scolarisation gratuite, y compris toutes sortes d\u2019activit\u00e9s extra-scolaire follement amusantes. J\u2019ai bien particip\u00e9 \u00e0 quelques <em>community services<\/em>, mais rien qui n\u2019\u00e9gale le co\u00fbt des services et infrastructures publics dont j\u2019ai profit\u00e9. Je n\u2019ai pas pay\u00e9 de taxes, je n\u2019ai pas particip\u00e9 \u00e0 l\u2019\u00e9conomie puisque je n\u2019ai pas travaill\u00e9, et en plus tous les frais de la vie quotidienne \u00e9taient couverts par ma famille d\u2019accueil b\u00e9n\u00e9vole. Pas fort. En Allemagne, l\u2019universit\u00e9 \u00e9tait gratuite, le transport tr\u00e8s peu co\u00fbteux, et je logeais dans une r\u00e9sidence subsidi\u00e9e par l\u2019Etat, tandis que j\u2019avais acc\u00e8s \u00e0 des repas \u00e0 tr\u00e8s bas prix \u00e0 la cantine universitaire. En plus, profiteuse que je suis, j\u2019ai eu droit aux tarifs \u00e9tudiants monstrueusement r\u00e9duits sur tous les \u00e9v\u00e9nements culturels. Scandaleux&nbsp;! Enfin, au Qu\u00e9bec, je travaille, mais pas assez pour payer des taxes, et on ne peut pas dire que mon boulot actuel soit particuli\u00e8rement qualifi\u00e9 ou vital \u00e0 la communaut\u00e9. J\u2019use et abuse des biblioth\u00e8ques, des routes, des patinoires et piscines publiques pour lesquelles je n\u2019ai jamais vers\u00e9 un rond. Comble du vampirisme, je prends des cours universitaires au tarif qu\u00e9b\u00e9cois<a href=\"#_ftn16\">[16]<\/a>, c\u2019est-\u00e0-dire bien en dessous du prix r\u00e9el. <strong>Force est de constater que je suis le mod\u00e8le m\u00eame de l\u2019immigrante qui profite du syst\u00e8me. Sauf que je parle la <\/strong><em><strong>bonne<\/strong><\/em><strong> langue, j\u2019ai la <\/strong><em><strong>bonne<\/strong><\/em><strong> couleur de peau, la <\/strong><em><strong>bonne<\/strong><\/em><strong> religion (ou absence de), la <\/strong><em><strong>bonne<\/strong><\/em><strong> nationalit\u00e9, et que mes parents ont la <\/strong><em><strong>bonne<\/strong><\/em><strong> somme dans leur compte en banque. <\/strong>Bien s\u00fbr, ceci est un exercice mental, on ne m\u2019a jamais accus\u00e9e de profiter du syst\u00e8me, et je ne m\u2019attends pas \u00e0 ce que cela arrive dans le futur. Mais cela d\u00e9montre que, malgr\u00e9 la rh\u00e9torique utilitariste de beaucoup de syst\u00e8mes d\u2019immigration, une certaine cat\u00e9gorie de personnes dont on ne parle pas passe entre les mailles du filet. C\u2019est le cas au Qu\u00e9bec gr\u00e2ce, notamment aux visas sans aucune exigence de qualification comme le mien, \u00e0 l\u2019accessibilit\u00e9 touristique du Canada pour certains pays (un.e touriste belge voulant visiter le Canada peut rester 6 mois sans encombre), mais aussi aux discours politiques franchement d\u00e9complex\u00e9s sur les immigrant.e.s d\u00e9sirables, comme le souhait du premier ministre qu\u00e9b\u00e9cois d\u2019importer plus d\u2019immigrant.e.s fran\u00e7ais.e.s, dont je vous parlais <a href=\"http:\/\/we-search.be\/index.php\/2019\/02\/20\/nommer-la-migration\/\">dans l\u2019article pr\u00e9c\u00e9dent<\/a>. <strong>La migration, quand bien m\u00eame elle se pr\u00e9sente comme \u00e9conomique, est filtr\u00e9e par des crit\u00e8res identitaires.<\/strong><\/p>\n\n\n\n<p><strong>Je ne pense pas qu\u2019on puisse vivre dans un monde pacifique et \u00e9galitaire tant que les int\u00e9r\u00eats et la souverainet\u00e9 de certains Etats sont sanctifi\u00e9s tandis que ceux d\u2019autres Etats ne sont pas consid\u00e9r\u00e9s pertinents. <\/strong>Je suis reconnaissante pour les opportunit\u00e9s de migration dont j\u2019ai b\u00e9n\u00e9fici\u00e9 \u2013 toutes ont suscit\u00e9 des questionnements, ont d\u00e9velopp\u00e9 mes sacro-saintes <em>soft skills<\/em>, et m\u2019ont permis de fonder une multitude de relations durables et profondes. <strong>Mais je suis un peu g\u00ean\u00e9e participer aveugl\u00e9ment au r\u00e9gime global des mobilit\u00e9s sans me questionner sur la l\u00e9gitimit\u00e9 et la d\u00e9sirabilit\u00e9 de mes d\u00e9placements,<\/strong> alors qu\u2019aucune de ces migrations n\u2019\u00e9tait particuli\u00e8rement m\u00e9rit\u00e9e, ni n\u00e9cessaire. Pourtant, je ne propose pas un monde o\u00f9 la mobilit\u00e9 ne devrait \u00eatre que m\u00e9rit\u00e9e et n\u00e9cessaire, bien au contraire, je sugg\u00e8re que nous nous questionnions sur l\u2019apposition de ces crit\u00e8res \u00e0 certains groupes de personnes et pas \u00e0 d\u2019autre, y compris nous-m\u00eame. <strong>La prochaine fois que vous vous d\u00e9placez \u00e0 l\u2019\u00e9tranger, demandez-vous&nbsp;: pourquoi je bouge&nbsp;? Qui m\u2019y autorise&nbsp;? \u00e0 qui cela b\u00e9n\u00e9ficie-t-il&nbsp;? Si mon profil sociologique ou les motifs de ma mobilit\u00e9 \u00e9taient l\u00e9g\u00e8rement diff\u00e9rents, serait-il plus facile, plus difficile de bouger&nbsp;? <\/strong><br><\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<p><a href=\"#_ftnref1\">[1]<\/a> Les r\u00e9fugi\u00e9.e.s r\u00e9install\u00e9.e.s ne repr\u00e9sentent qu\u2019une tr\u00e8s petite\nfraction des personnes d\u00e9plac\u00e9es de force dans le monde, et sont tri\u00e9.e.s en\nfonction de crit\u00e8res du HCR et de ceux impos\u00e9s par les pays d\u2019accueil. Pour en\nsavoir plus, voir <a href=\"https:\/\/www.unhcr.org\/resettlement-data.html\">https:\/\/www.unhcr.org\/resettlement-data.html<\/a><\/p>\n\n\n\n<p><a href=\"#_ftnref2\">[2]<\/a> AUSTEN, Ian, \u00ab Syrian Refugees Greeted by Justin Trudeau in\nCanada&nbsp;\u00bb, <em>The New York Times<\/em>, 11\nd\u00e9cembre 2015 <a href=\"https:\/\/www.nytimes.com\/2015\/12\/12\/world\/americas\/syria-refugees-arrive-in-canada.html\">https:\/\/www.nytimes.com\/2015\/12\/12\/world\/americas\/syria-refugees-arrive-in-canada.html<\/a><\/p>\n\n\n\n<p><a href=\"#_ftnref3\">[3]<\/a> La protection subsidiaire existe dans de nombreux pays comme une mani\u00e8re\nde reconnaitre qu\u2019une personne a besoin de la protection de l\u2019Etat sans lui accorder\nles droits complets du statut de r\u00e9fugi\u00e9 \u2013 c\u2019est notamment une protection moins\n\u00e9tendue dans le temps. En Belgique, 9% des demandeurs.euses d\u2019asile ont obtenu\nla protection subsidiaire en 2018, qui est initialement valide 1 an (et doit\nensuite \u00eatre renouvel\u00e9e) au lieu des 5 ans habituels du statut de r\u00e9fugi\u00e9. Source&nbsp;:\nCGRA, <em>Statistiques d\u2019asile \u2013 Bilan 2018<\/em>\n<a href=\"https:\/\/www.cgra.be\/fr\/actualite\/statistiques-dasile-bilan-2018\">https:\/\/www.cgra.be\/fr\/actualite\/statistiques-dasile-bilan-2018<\/a>\n<\/p>\n\n\n\n<p><a href=\"#_ftnref4\">[4]<\/a> Voir COHEN, Gerard Daniel, <em>In War\u2019s\nWake<\/em>, Oxford, UK, Oxford University Press, 2011, 248p.<\/p>\n\n\n\n<p><a href=\"#_ftnref5\">[5]<\/a> AKOKA, Karen, \u00ab&nbsp;Distinguer les r\u00e9fugi\u00e9s\ndes migrants au XX\u00e8 si\u00e8cle&nbsp;: Enjeux et usages des politiques de\nclassification&nbsp;\u00bb, pp. 47-68, dans AGIER, Michel, MADEIRA, Anne-Virginie\n(dir.), <em>D\u00e9finir les r\u00e9fugi\u00e9s<\/em>, Paris,\nPresses Universitaires de France, coll. La vie des\nid\u00e9es, 2017.<\/p>\n\n\n\n<p><a href=\"#_ftnref6\">[6]<\/a>NASSER, Shanifa, \u00ab&nbsp;Who benefits from rescuing Rahaf? Questions\nlinger after whirlwind story of Saudi teen&rsquo;s asylum&nbsp;\u00bb, <em>CBC News<\/em>, 14 Janvier 2019, cbc.ca\/news\/canada\/toronto\/rahaf-al-qunun-canada-saudi-refugee-1.4976735\n<\/p>\n\n\n\n<p><a href=\"#_ftnref7\">[7]<\/a> Par exemple, cette campagne allemande fait la promotion maladroite de\nl\u2019emploi des r\u00e9fugi\u00e9s avec son slogan \u00ab&nbsp;Soft Skills can come the hard\nway&nbsp;\u00bb, signifiant que les difficult\u00e9s par lesquelles sont pass\u00e9es les\npersonnes d\u00e9plac\u00e9es de force les rendent plus comp\u00e9tents <a href=\"http:\/\/employ-refugees.de\/\">http:\/\/employ-refugees.de\/<\/a>\n<\/p>\n\n\n\n<p><a href=\"#_ftnref8\">[8]<\/a> AKOKA, Karen, <em>op.cit.<\/em><\/p>\n\n\n\n<p><a href=\"#_ftnref9\">[9]<\/a> Pour plus d\u2019informations, voir <a href=\"https:\/\/resettlement.de\/en\/resettlement-2\/\">https:\/\/resettlement.de\/en\/resettlement-2\/<\/a><\/p>\n\n\n\n<p><a href=\"#_ftnref10\">[10]<\/a> WESTON PHIPPEN, J., \u00ab&nbsp;Australia\u2019s Controversial Migration\nPolicy&nbsp;\u00bb, <em>The Atlantic<\/em>, 29 avril\n2016, <a href=\"https:\/\/www.theatlantic.com\/international\/archive\/2016\/04\/australia-immigration\/480189\/\">https:\/\/www.theatlantic.com\/international\/archive\/2016\/04\/australia-immigration\/480189\/<\/a>\n<\/p>\n\n\n\n<p><a href=\"#_ftnref11\">[11]<\/a> BEZAT, Jean-Michel, \u00ab Le tourisme international a connu une forte\nprogression en 2018&nbsp;\u00bb, <em>Le Monde<\/em>,\n22 janvier 2019, <a href=\"https:\/\/www.lemonde.fr\/economie\/article\/2019\/01\/22\/le-tourisme-international-a-connu-une-forte-progression-en-2018_5412842_3234.html\">https:\/\/www.lemonde.fr\/economie\/article\/2019\/01\/22\/le-tourisme-international-a-connu-une-forte-progression-en-2018_5412842_3234.html<\/a>\n<\/p>\n\n\n\n<p><a href=\"#_ftnref12\">[12]<\/a> Statistiques du Haut Commissariat aux R\u00e9fugi\u00e9s <a href=\"https:\/\/www.unhcr.org\/figures-at-a-glance.html\">https:\/\/www.unhcr.org\/figures-at-a-glance.html<\/a><\/p>\n\n\n\n<p><a href=\"#_ftnref13\">[13]<\/a> ROSENBERG, Tina, \u00ab&nbsp;The business of voluntourism: do western\ndo-gooders actually do harm?&nbsp;\u00bb, <em>The\nGuardian<\/em>, 13 septembre 2018, <a href=\"https:\/\/www.theguardian.com\/news\/2018\/sep\/13\/the-business-of-voluntourism-do-western-do-gooders-actually-do-harm\">https:\/\/www.theguardian.com\/news\/2018\/sep\/13\/the-business-of-voluntourism-do-western-do-gooders-actually-do-harm<\/a>\n<\/p>\n\n\n\n<p><a href=\"#_ftnref14\">[14]<\/a> Voir Mostafanezhad, Mary,\n\u00ab Volunteer tourism and the popular humanitarian gaze&nbsp;\u00bb, <em>Geoforum<\/em>, Vol. 54, 2014, pp. 111-118.<\/p>\n\n\n\n<p><a href=\"#_ftnref15\">[15]<\/a> GARDNER, Andrew, \u00ab Why Do They Keep Coming? Labor Migrants in the\nGulf States&nbsp;\u00bb, in KAMRAVA, Mehran, BABAR, Zahra (eds), <em>Migrant Labor in the Persian Gulf<\/em>,\nLondon, UK, C. Hurst &amp; Co., 2012.<\/p>\n\n\n\n<p><a href=\"#_ftnref16\">[16]<\/a> La Belgique a r\u00e9cemment sign\u00e9 un accord calqu\u00e9 sur celui qui existait\nd\u00e9j\u00e0 avec la France, pour permettre aux ressortissant.e.s d\u2019un pays de profiter\nd\u2019une \u00e9ducation au tarif local.<\/p>\n<span class=\"et_bloom_bottom_trigger\"><\/span>","protected":false},"excerpt":{"rendered":"<p>Par&nbsp;Elo\u00efse&nbsp;Goffart,&nbsp;dipl\u00f4m\u00e9e&nbsp;en&nbsp;sciences&nbsp;politiques Je suis n\u00e9e dans l\u2019espace Schengen. Mon enfance \u00e9tait confortablement berc\u00e9e de s\u00e9jours dans les stations de ski alpines en France, de visites aux amis allemands de ma m\u00e8re,<a class=\"moretag\" href=\"https:\/\/we-search.be\/index.php\/2019\/05\/14\/pourquoi-on-migre-de-linegale-legitimite-des-mobilites\/\"><span class=\"screen-reader-text\">En savoir plus surPourquoi on migre \u2013 de l\u2019in\u00e9gale l\u00e9gitimit\u00e9 des mobilit\u00e9s<\/span>[&#8230;]<\/a><\/p>\n","protected":false},"author":4,"featured_media":420837,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4],"tags":[83,82,74,79,61,81,80,78],"class_list":["post-387736","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-we-discuss","tag-apprentissage","tag-canada","tag-erasmus","tag-legitimite","tag-migration","tag-schengen","tag-sociologie","tag-voyage"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/we-search.be\/wp-content\/uploads\/2019\/05\/man-relaxation-meditation-rotterdam-new-mesh-erasmus-bridge-1589341-pxhere.com_.jpg?fit=3000%2C1691&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9cJNf-1CRO","jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/we-search.be\/index.php\/wp-json\/wp\/v2\/posts\/387736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/we-search.be\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/we-search.be\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/we-search.be\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/we-search.be\/index.php\/wp-json\/wp\/v2\/comments?post=387736"}],"version-history":[{"count":3,"href":"https:\/\/we-search.be\/index.php\/wp-json\/wp\/v2\/posts\/387736\/revisions"}],"predecessor-version":[{"id":420838,"href":"https:\/\/we-search.be\/index.php\/wp-json\/wp\/v2\/posts\/387736\/revisions\/420838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/we-search.be\/index.php\/wp-json\/wp\/v2\/media\/420837"}],"wp:attachment":[{"href":"https:\/\/we-search.be\/index.php\/wp-json\/wp\/v2\/media?parent=387736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/we-search.be\/index.php\/wp-json\/wp\/v2\/categories?post=387736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/we-search.be\/index.php\/wp-json\/wp\/v2\/tags?post=387736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}